{"id":13178,"date":"2017-11-06T19:01:59","date_gmt":"2017-11-06T18:01:59","guid":{"rendered":"http:\/\/www.bmscience.net\/blog\/?p=13178"},"modified":"2024-02-20T22:14:07","modified_gmt":"2024-02-20T21:14:07","slug":"la-velocita-delle-onde-gravitazionali","status":"publish","type":"post","link":"https:\/\/www.bmscience.net\/blog\/la-velocita-delle-onde-gravitazionali\/","title":{"rendered":"La velocit\u00e0 delle Onde Gravitazionali"},"content":{"rendered":"\n<p>Durante lo scorso mese non si \u00e8 sentito parlare di altro: Onde gravitazionali.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"996\" height=\"559\" src=\"https:\/\/www.bmscience.net\/blog\/wp-content\/uploads\/2017\/11\/figure1.jpg\" alt=\"\" class=\"wp-image-13179\" srcset=\"https:\/\/www.bmscience.net\/blog\/wp-content\/uploads\/2017\/11\/figure1.jpg 996w, https:\/\/www.bmscience.net\/blog\/wp-content\/uploads\/2017\/11\/figure1-300x168.jpg 300w, https:\/\/www.bmscience.net\/blog\/wp-content\/uploads\/2017\/11\/figure1-768x431.jpg 768w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/><figcaption class=\"wp-element-caption\">Immagine di: NASA<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-left\">Le onde gravitazionali sono distorsioni dello spaziotempo causate da un oggetti dotati di massa. Normalmente sono impercettibili, tranne nel caso di eventi cosmici, come supernovae o collisione di buchi neri.<\/p>\n\n\n<div id=\"bmscience3333198660\" style=\"margin-top: 15px;margin-left: 15px;float: right;\"><a href=\"https:\/\/amzn.to\/40Y3cl4\" target=\"_blank\" aria-label=\"Progetto senza titolo\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bmscience.net\/blog\/wp-content\/uploads\/2025\/08\/Progetto-senza-titolo-1.gif\" alt=\"\"  width=\"300\" height=\"250\"   \/><\/a><\/div>\n\n\n<p class=\"has-text-align-left\">Negli ultimi due anni gli astronomi del LIGO (Stati Uniti) e del VIRGO (Italia) sono riusciti a osservare quattro fonti di onde gravitazionali, l&#8217;ultima dei quali ci ha fornito molte informazioni sull&#8217;universo.<br>L&#8217;ultima rilevazione \u00e8 stata causata dalla collisione di due stelle di neutroni. Questo evento non solo \u00e8 stato registrato dagli interferometri laser, con lo scopo di misurare le onde gravitazionali, ma anche dai telescopi. In questo modo gli scienziati sono stati in grado di misurare e comparare le rispettive velocit\u00e0.<\/p>\n\n\n\n<p class=\"has-text-align-left\">La fisica Newtoniana prevedeva che la gravit\u00e0 avesse un&#8217;azione istantanea, pi\u00f9 tardi Albert Einstein teorizz\u00f2 che anche l&#8217;azione gravitazionale si sarebbe dovuta propagare nello spazio.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Questi esperimenti, non solo hanno confermato la teoria di Einstein, ma hanno anche misurato la velocit\u00e0 delle onde gravitazionali, che \u00e8 pari a &#8220;c&#8221;, con un margine di errore bassissimo, praticamente \u00e8 uguale alla velocit\u00e0 della luce, rimanendo quindi coerente alla teoria della relativit\u00e0 generale di Einstein.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Questa \u00e8 una conquista nel campo della astrofisica, che in questi ultimi tempi compie passi da gigante, anche grazie a strumenti sempre pi\u00f9 sofisticati.<\/p>\n\n\n\n<p class=\"has-text-align-left\">Consiglio anche la visione di questi due video del canale Veritasium. Sono presenti i sottotitoli in Italiano.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Neutron Star Merger Gravitational Waves and Gamma Rays\" width=\"768\" height=\"432\" src=\"https:\/\/www.youtube.com\/embed\/EAyk2OsKvtU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Absurdity of Detecting Gravitational Waves\" width=\"768\" height=\"432\" src=\"https:\/\/www.youtube.com\/embed\/iphcyNWFD10?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<div id=\"bmscience3734983203\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3495866718878812\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3495866718878812\" \ndata-ad-slot=\"4682122636\" \ndata-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Durante lo scorso mese non si \u00e8 sentito parlare di altro: Onde gravitazionali. Le onde gravitazionali sono distorsioni dello spaziotempo causate da un oggetti dotati di massa. Normalmente sono impercettibili, tranne nel caso di eventi cosmici, come supernovae o collisione di buchi neri. Negli ultimi due anni gli astronomi del LIGO (Stati Uniti) e del&hellip;<\/p>\n<p class=\"more\"><a class=\"more-link\" href=\"https:\/\/www.bmscience.net\/blog\/la-velocita-delle-onde-gravitazionali\/\">Continue reading <span class=\"screen-reader-text\">La velocit\u00e0 delle Onde Gravitazionali<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[30],"tags":[822,2627,5328,6308,7146],"class_list":["post-13178","post","type-post","status-publish","format-standard","hentry","category-spazio","tag-astrofisica","tag-einstein","tag-onde-gravitazionali","tag-relativita-generale","tag-stelle-di-neutroni","entry"],"author_meta":{"display_name":"Stefano","author_link":"https:\/\/www.bmscience.net\/blog\/author\/stefano\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">Spazio<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Spazio<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">astrofisica<\/a>","<a href=\"https:\/\/www.bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">einstein<\/a>","<a href=\"https:\/\/www.bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">onde gravitazionali<\/a>","<a href=\"https:\/\/www.bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">relativit\u00e0 generale<\/a>","<a href=\"https:\/\/www.bmscience.net\/blog\/category\/spazio\/\" class=\"advgb-post-tax-term\">stelle di neutroni<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">astrofisica<\/span>","<span class=\"advgb-post-tax-term\">einstein<\/span>","<span class=\"advgb-post-tax-term\">onde gravitazionali<\/span>","<span class=\"advgb-post-tax-term\">relativit\u00e0 generale<\/span>","<span class=\"advgb-post-tax-term\">stelle di neutroni<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Pubblicato 9 anni fa","modified":"Aggiornato 2 anni fa"},"absolute_dates":{"created":"Pubblicato il 06\/11\/2017","modified":"Aggiornato il 20\/02\/2024"},"absolute_dates_time":{"created":"Pubblicato il 06\/11\/2017 19:01","modified":"Aggiornato il 20\/02\/2024 22:14"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/posts\/13178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/comments?post=13178"}],"version-history":[{"count":0,"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/posts\/13178\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/media?parent=13178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/categories?post=13178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bmscience.net\/blog\/wp-json\/wp\/v2\/tags?post=13178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}